{"id":1441,"date":"2021-09-28T09:48:14","date_gmt":"2021-09-28T09:48:14","guid":{"rendered":"https:\/\/lojaespacos.com\/?post_type=product&#038;p=1441"},"modified":"2026-01-29T16:41:04","modified_gmt":"2026-01-29T16:41:04","slug":"harmo-splen-f-hs1-tcm-formula-50ml-estomago-baco-pancreas-terra","status":"publish","type":"product","link":"https:\/\/lojaespacos.com\/en\/loja\/fitoterapia-oriental\/fitoterapia-chinesa\/harmo-splen-f-hs1-tcm-formula-50ml-estomago-baco-pancreas-terra\/","title":{"rendered":"Harmo Splen (F-Hs1) | TCM Formula | 50mL | est\u00f4mago\/ba\u00e7o\/p\u00e2ncreas | terra"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Harmo Splen\u00a0(F-Hs1)<\/strong>\u00a0\u00e9 uma f\u00f3rmula de\u00a0<strong>Chinese herbal medicine\u00a0<\/strong>que ajuda a equilibrar, do ponto de vista<strong>\u00a0f\u00edsico e energ\u00e9tico<\/strong>, \u00a0o sistema\u00a0<strong>Est\u00f4mago\/Ba\u00e7o\/P\u00e2ncreas<\/strong>. Harmoniza o movimento<strong>\u00a0terra<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Apresenta\u00e7\u00e3o<\/strong>: 50mL.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredientes<\/strong>: \u00c1gua; extracto concentrado fitoactivo (10%) de:\u00a0<em>Dioscoreae oppositae<\/em>\u00a0(rizoma),\u00a0<em>Amomi villosi\u00a0<\/em>(fruto),\u00a0<em>Pinelliae preparatum\u00a0<\/em>(rizoma),\u00a0<em>Coptidis<\/em>\u00a0(rizoma),\u00a0<em>Zingiberis exsiccatum<\/em>\u00a0(rizoma),\u00a0<em>Salviae miltiorrhizae<\/em>\u00a0(raiz),\u00a0<em>Puerariae<\/em>\u00a0(raiz). Glicerina 1%; \u00e1lcool 0,5%.<\/p>\n<p style=\"text-align: justify;\"><strong>Posologia\u00a0<\/strong>(salvo indica\u00e7\u00e3o em contr\u00e1rio por parte do terapeuta): tomar 30 gotas dilu\u00eddas em \u00e1gua, duas vezes ao dia.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Aviso: <\/strong>Dever\u00e1 consultar um <strong>especialista<\/strong> em <strong>Medicina Tradicional Chinesa<\/strong>, para poder saber qual a <strong>f\u00f3rmula mais adequada<\/strong> \u00e0 sua situa\u00e7\u00e3o. <strong>Evite a auto-prescri\u00e7\u00e3o.\u00a0<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Harmo Splen\u00a0(F-Hs1)\u00a0\u00e9 uma f\u00f3rmula de\u00a0fitoterapia chinesa\u00a0que ajuda a equilibrar, do ponto de vista\u00a0f\u00edsico e energ\u00e9tico, \u00a0o sistema\u00a0Est\u00f4mago\/Ba\u00e7o\/P\u00e2ncreas. Harmoniza o movimento\u00a0terra. Apresenta\u00e7\u00e3o: 50mL. Ingredientes: \u00c1gua; extracto concentrado fitoactivo (10%) de:\u00a0Dioscoreae oppositae\u00a0(rizoma),\u00a0Amomi villosi\u00a0(fruto),\u00a0Pinelliae preparatum\u00a0(rizoma),\u00a0Coptidis\u00a0(rizoma),\u00a0Zingiberis exsiccatum\u00a0(rizoma),\u00a0Salviae miltiorrhizae\u00a0(raiz),\u00a0Puerariae\u00a0(raiz). Glicerina 1%; \u00e1lcool 0,5%. Posologia\u00a0(salvo indica\u00e7\u00e3o em contr\u00e1rio por parte do terapeuta): tomar 30 gotas dilu\u00eddas em \u00e1gua, duas vezes ao [&hellip;]<\/p>\n","protected":false},"featured_media":1485,"comment_status":"open","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"%%sitetitle%% | %%post_title%%","_seopress_titles_desc":"%%post_content%%","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"est\u00f4mago,ba\u00e7o,p\u00e2ncreas,fitoterapia chinesa,suplemento chin\u00eas,rem\u00e9dio chin\u00eas,rem\u00e9dio para o est\u00f4mago,f\u00f3rmula chinesa,movimento terra,medicina chinesa,plantas da medicina chinesa,f\u00f3rmulas da medicina chinesa,medicina tradicional chinesa"},"product_brand":[],"product_cat":[821,820,824],"product_tag":[],"hf_cat_product":[],"class_list":["post-1441","product","type-product","status-publish","has-post-thumbnail","product_cat-fitoterapia-chinesa","product_cat-fitoterapia-oriental","product_cat-tcm-formula","first","outofstock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/product\/1441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/comments?post=1441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/media\/1485"}],"wp:attachment":[{"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/media?parent=1441"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/product_brand?post=1441"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/product_cat?post=1441"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/product_tag?post=1441"},{"taxonomy":"hf_cat_product","embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/hf_cat_product?post=1441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}