{"id":1439,"date":"2021-09-28T09:48:14","date_gmt":"2021-09-28T09:48:14","guid":{"rendered":"https:\/\/lojaespacos.com\/?post_type=product&#038;p=1439"},"modified":"2026-01-29T16:43:29","modified_gmt":"2026-01-29T16:43:29","slug":"harmo-reno-f-hr1-tcm-formula-50ml-rim-bexiga-agua","status":"publish","type":"product","link":"https:\/\/lojaespacos.com\/en\/loja\/fitoterapia-oriental\/fitoterapia-chinesa\/harmo-reno-f-hr1-tcm-formula-50ml-rim-bexiga-agua\/","title":{"rendered":"Harmo Reno (F-Hr1) | TCM Formula | 50mL | rim\/bexiga | \u00e1gua"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Harmo Reno (F-Hr1)<\/strong>\u00a0\u00e9 uma f\u00f3rmula de\u00a0<strong>Chinese herbal medicine<\/strong>\u00a0que ajuda a equilibrar, do ponto de vista\u00a0<strong>f\u00edsico e energ\u00e9tico<\/strong>, \u00a0o sistema\u00a0<strong>Rim\/Bexiga<\/strong>. Harmoniza o movimento\u00a0<strong>\u00e1gua<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Apresenta\u00e7\u00e3o<\/strong>: 50mL.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredientes:<\/strong>\u00a0\u00c1gua; extracto concentrado fitoactivo (10%) de:\u00a0<em>Ostreae<\/em>\u00a0(concha),\u00a0<em>Zizyphi jujubae<\/em>\u00a0(fruto),\u00a0<em>Ecliptae<\/em>\u00a0(erva),\u00a0<em>Epimedii<\/em>\u00a0(erva), Talco,\u00a0<em>Paeoniae albae<\/em>\u00a0(raiz),\u00a0<em>Poriae albae<\/em>\u00a0(cogumelo). Glicerina 1%; \u00e1lcool 0,5%.<\/p>\n<p style=\"text-align: justify;\"><strong>Posologia\u00a0<\/strong>(salvo indica\u00e7\u00e3o em contr\u00e1rio por parte do terapeuta): tomar 30 gotas dilu\u00eddas em \u00e1gua, duas vezes ao dia.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Aviso: <\/strong>Dever\u00e1 consultar um <strong>especialista<\/strong> em <strong>Medicina Tradicional Chinesa<\/strong>, para poder saber qual a <strong>f\u00f3rmula mais adequada<\/strong> \u00e0 sua situa\u00e7\u00e3o. <strong>Evite a auto-prescri\u00e7\u00e3o.\u00a0<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Harmo Reno (F-Hr1)\u00a0\u00e9 uma f\u00f3rmula de\u00a0fitoterapia chinesa\u00a0que ajuda a equilibrar, do ponto de vista\u00a0f\u00edsico e energ\u00e9tico, \u00a0o sistema\u00a0Rim\/Bexiga. Harmoniza o movimento\u00a0\u00e1gua. Apresenta\u00e7\u00e3o: 50mL. Ingredientes:\u00a0\u00c1gua; extracto concentrado fitoactivo (10%) de:\u00a0Ostreae\u00a0(concha),\u00a0Zizyphi jujubae\u00a0(fruto),\u00a0Ecliptae\u00a0(erva),\u00a0Epimedii\u00a0(erva), Talco,\u00a0Paeoniae albae\u00a0(raiz),\u00a0Poriae albae\u00a0(cogumelo). Glicerina 1%; \u00e1lcool 0,5%. Posologia\u00a0(salvo indica\u00e7\u00e3o em contr\u00e1rio por parte do terapeuta): tomar 30 gotas dilu\u00eddas em \u00e1gua, duas vezes ao dia. [&hellip;]<\/p>\n","protected":false},"featured_media":1479,"comment_status":"open","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"%%sitetitle%% | %%post_title%%","_seopress_titles_desc":"%%post_content%%","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"rim,rins,bexiga,movimento \u00e1gua,medicina chinesa,medicina tradicional chinesa,f\u00f3rmula chinesa,f\u00f3rmula mtc,suplemento,rem\u00e9dio,fitoterapia chinesa,rem\u00e9dio para os rins,rem\u00e9dio para a bexiga"},"product_brand":[],"product_cat":[821,820,824],"product_tag":[],"hf_cat_product":[],"class_list":["post-1439","product","type-product","status-publish","has-post-thumbnail","product_cat-fitoterapia-chinesa","product_cat-fitoterapia-oriental","product_cat-tcm-formula","first","outofstock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/product\/1439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/comments?post=1439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/media\/1479"}],"wp:attachment":[{"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/media?parent=1439"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/product_brand?post=1439"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/product_cat?post=1439"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/product_tag?post=1439"},{"taxonomy":"hf_cat_product","embeddable":true,"href":"https:\/\/lojaespacos.com\/en\/wp-json\/wp\/v2\/hf_cat_product?post=1439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}